{"id":9039,"date":"2022-11-14T23:09:53","date_gmt":"2022-11-15T02:09:53","guid":{"rendered":"https:\/\/fotodepenis.com\/?p=9039"},"modified":"2022-11-14T23:09:53","modified_gmt":"2022-11-15T02:09:53","slug":"o-segredo-do-meu-irmaozinho-parte-3","status":"publish","type":"post","link":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/","title":{"rendered":"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3"},"content":{"rendered":"<p>eu morria de \u00f3dio daquilo!<\/p>\n<p>Durante uma manh\u00e3 t\u00edpica de domingo<\/p>\n<p>na fazenda, minha m\u00e3e, av\u00f3 e tias e tios<br \/>\nparticipavam de uma missa numa igreja<br \/>\npr\u00f3xima \u2014 que n\u00e3o era t\u00e3o pr\u00f3xima assim,<br \/>\nembora fosse a mais pr\u00f3xima da fazenda<\/p>\n<p>\u2014 enquanto Gabriel, eu e alguns primos<br \/>\nfic\u00e1vamos em casa mesmo.<\/p>\n<p>Gabriel e R\u00f3bson, normalmente iam para o<br \/>\nrio, que ficava a uns quinze minutos da casa,<br \/>\nnadar juntos. Quando \u00e9ramos crian\u00e7as eu<br \/>\nos acompanhava e tudo que faz\u00edamos l\u00e1 era<br \/>\nnadar e jogar \u00e1gua uns nos outros. Naquela<br \/>\n\u00e9poca podia ser divertido e engra\u00e7ado,<\/p>\n<p>mas para mim n\u00e3o era mais. Ent\u00e3o eu<\/p>\n<p>n\u00e3o perdia meu tempo \u00e0queles beb\u00eas de<br \/>\nproveta. Quando me levantei procurei por<br \/>\nGabriel e n\u00e3o o encontrei. N\u00e3o sei explicar<br \/>\nat\u00e9 hoje porque naquele dia eu tive vontade<br \/>\nde procura-lo, parecia que realmente estava<br \/>\nescrito que eu precisava \u201cdescobri-lo\u201d.<br \/>\nTomei um caf\u00e9 r\u00e1pido e depois fui<br \/>\ncaminhando at\u00e9 a regi\u00e3o do rio. Sabia que<br \/>\neu ia encontrar Gabriel e R\u00f3bson l\u00e1, nadando<br \/>\ne jogando \u00e1gua um no outro, como sempre<br \/>\nfaziam. Quando cheguei l\u00e1 perto pude<\/p>\n<p>ver os dois. Estavam pelados, o que era<br \/>\ncompletamente natural, j\u00e1 que normalmente<br \/>\no pessoal nadava mesmo sem roupa<br \/>\nnenhuma naquele rio. E como eu imaginava,<br \/>\nestavam rindo atoa e jogando \u00e1gua um<\/p>\n<p>no outro, se empurrando e brincando de<br \/>\n\u201clutinha\u201d, igual faz\u00edamos os tr\u00eas, anos e anos<br \/>\nantes.<\/p>\n<p>De repente, eles pararam e R\u00f3bson ent\u00e3o<br \/>\nfalou:<\/p>\n<p>\u2014 Vou pegar um cigarro.<\/p>\n<p>\u2014 T\u00e1. \u2014 Gabriel respondeu.<br \/>\nE ent\u00e3o quando ouvi a palavra \u201ccigarro\u201d, me<br \/>\nescondi entre algumas \u00e1rvores que ficavam<br \/>\npr\u00f3ximas do rio. Na hora eu n\u00e3o entendi<br \/>\nnada e nem mesmo tentei entender, apenas<br \/>\nfiquei observando o que fariam a seguir.<br \/>\nR\u00f3bson saiu do rio e foi at\u00e9 as roupas que<br \/>\nestavam penduradas em uma \u00e1rvore que<br \/>\nficava na margem do rio. De dentro do<br \/>\nbolso de sua bermuda, vi muito bem que ele<br \/>\nretirou um ma\u00e7o de cigarros e um isqueiro.<br \/>\nNa nossa fam\u00edlia n\u00e3o havia fumantes e me<br \/>\nsurpreendia o fato de R\u00f3bson, aos dezesseis<br \/>\nanos, fumasse.<\/p>\n<p>R\u00f3bson retirou do ma\u00e7o um cigarro e p\u00f4s<br \/>\nna boca, entre seus l\u00e1bios grossos. Eu, que<br \/>\ntinha vontade de fumar, e um louco fetiche<br \/>\npor fumantes, fiquei embasbacado com a<br \/>\nideia. Nunca imaginei nosso primo fumando.<br \/>\nE mesmo n\u00e3o tendo \u2014 ao menos at\u00e9 aquele<br \/>\nmomento \u2014 nenhum interesse em outros<br \/>\nhomens, tive uma ere\u00e7\u00e3o instant\u00e2nea com<br \/>\naquela cena. Naturalmente, mostrando que<br \/>\nn\u00e3o estava experimentando, e sim j\u00e1 era um<br \/>\nfumante experiente, R\u00f3bson usou o isqueiro<br \/>\ne acendeu corretamente de primeira o seu<br \/>\ncigarro. Lembro-me t\u00e3o bem da cena, que<br \/>\nn\u00e3o pude deixar de observar que o ma\u00e7o<br \/>\nera um Hollywood Vermelho Cl\u00e1ssico, com<br \/>\ncigarros com aquele filtro alaranjado (para<br \/>\nquem fuma, sabe que n\u00e3o \u00e9 um cigarro para<br \/>\nse come\u00e7ar, j\u00e1 que \u00e9 bem forte). R\u00f3bson<br \/>\ntragou e soltou uma densa fuma\u00e7a no rosto<br \/>\ndo meu irm\u00e3ozinho Gabriel, em seguida<br \/>\ndisse algo que n\u00e3o consegui compreender,<br \/>\nmas que fez meu irm\u00e3o cair na gargalhada.<br \/>\nEm seguida R\u00f3bson entregou o ma\u00e7o de<br \/>\nHollywood nas m\u00e3os de Gabriel e foi ai<\/p>\n<p>que meu cora\u00e7\u00e3o disparou e quase saiu<\/p>\n<p>pela boca. A primeira impress\u00e3o que tive<br \/>\nera que Gabs ia apenas segurar o ma\u00e7o,<br \/>\npois ele ainda estava rindo atoa com o que<br \/>\nquer que fosse que R\u00f3bson tinha dito. Mas<br \/>\nnaturalmente, meu irm\u00e3ozinho magricelo<\/p>\n<p>e mi\u00fado de quatorze anos, aquele anjinho<br \/>\nperfeitinho e inocente, tamb\u00e9m retirou um<br \/>\ncigarro do ma\u00e7o e ainda t\u00e3o naturalmente,<br \/>\ncomo R\u00f3bson, o colocou entre os l\u00e1bios<br \/>\nfinos e delicados, tentando parar de rir da<br \/>\ntal piada do primo. E em seguida, R\u00f3bson<br \/>\nrecolheu o ma\u00e7o das m\u00e3os de Gabs e<br \/>\npassou o isqueiro. Meu irm\u00e3ozinho, t\u00e3o<br \/>\nexperiente quanto o primo, acendeu o<br \/>\ncigarro com a pontinha da chama do<br \/>\nisqueiro, tragou e soltou a primeira baforada<br \/>\nde fuma\u00e7a. E os dois sorriam um para o<br \/>\noutro.<\/p>\n<p>Naquele momento minha press\u00e3o arterial<br \/>\ndeve ter baixado, pois senti tudo girando<\/p>\n<p>a meu redor, inclusive aquela cena, meu<br \/>\nirm\u00e3ozinho ca\u00e7ula, o filho perfeitinho e o<br \/>\nanjinho que todos amavam , ali, pelado, com<br \/>\no primo e fumando!<\/p>\n<p>Os dois continuavam conversando<br \/>\nnaturalmente, envoltos de longas tragadas<br \/>\ne fuma\u00e7as. Eu j\u00e1 tinha visto muitos colegas<br \/>\nfumando. Os que j\u00e1 fumavam h\u00e1 mais<br \/>\ntempo conseguiam criar aquele cone de<br \/>\nfuma\u00e7a, mais longo e mais denso. Os mais<br \/>\ninexperientes, que fumavam h\u00e1 pouco<br \/>\ntempo &#8211; ou que estavam aprendendo ainda<br \/>\na tragar \u2014 n\u00e3o conseguiam fazer essa<br \/>\nmesma densidade de fuma\u00e7a quando a<br \/>\nsoltavam ap\u00f3s a tragada.<\/p>\n<p>E o que me surpreendeu \u00e9 que Gabriel<br \/>\nconseguia com naturalidade e \u00eaxito dar<br \/>\naquela tragada demorada, entre cinco e<\/p>\n<p>sete segundos, e soltava aquela fuma\u00e7a<br \/>\nimponente e densa, que era vis\u00edvel de onde<br \/>\neu estava escondido. O que me revelava,<br \/>\nmesmo eu nunca tendo acendido um cigarro<br \/>\nna vida, que ele era um fumante experiente,<br \/>\nn\u00e3o era mesmo sua primeira tragada! Mas<br \/>\nque porra, quando aquele moleque, santinho<br \/>\ndo pau oco tinha come\u00e7ado a fumar? Depois<br \/>\nde passar os sintomas daquela revela\u00e7\u00e3o,<br \/>\nabaixei-me e continuei espiando, tentando<br \/>\nser o mais silencioso poss\u00edvel, para que eles<br \/>\nn\u00e3o pudessem me descobrir.<\/p>\n<p>A raiva que eu sentia do meu irm\u00e3ozinho<br \/>\nGabs j\u00e1 era enorme, naquele momento<br \/>\nestava sendo multiplicada por mil, pois<\/p>\n<p>todo aquele jeitinho de anjinho e inoc\u00eancia<br \/>\nera uma porra de m\u00e1scara! Imaginei a<\/p>\n<p>nossa m\u00e3e vendo aquilo. Se ela visse<br \/>\nGabriel fumando, com certeza morreria de<br \/>\ndesgosto. Tive pena da minha velha naquele<br \/>\nmomento, mesmo que ela n\u00e3o merecesse.<br \/>\nFilho da puta. Anjinho do pau oco. Moleque<br \/>\nbost\u00e3o. Put\u00e3o maldito. Pagava de inocente<br \/>\ne era um filha da puta de um fumante do<br \/>\ncaralho.<\/p>\n<p>O pior \u00e9 que o pior ainda n\u00e3o tinha<br \/>\nacontecido. De repente, Gabriel e R\u00f3bson<br \/>\njogaram suas guimbas (j\u00e1 pequenas,<\/p>\n<p>bem fumadas) no rio e recome\u00e7aram a<br \/>\nbrincadeira de \u201clutinha\u201d. Os dois come\u00e7aram<br \/>\na se agarrar e riam pra caralho com aquela<br \/>\nbrincadeira. Eu tive que esfregar os olhos<br \/>\npara ver se era realmente verdade aquilo que<br \/>\neu estava enxergando: R\u00f3bson, nosso primo<br \/>\navantajado e musculoso, e Gabriel, meu<br \/>\nirm\u00e3ozinho ca\u00e7ula magricelo e miudinho<br \/>\ncome\u00e7aram a se beijar na boca!<\/p>\n<p>N\u00e3o era s\u00f3 boca, era l\u00edngua e saliva tamb\u00e9m,<br \/>\nContinua&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>eu morria de \u00f3dio daquilo! Durante uma manh\u00e3 t\u00edpica de domingo na fazenda, minha m\u00e3e, av\u00f3 e tias e tios participavam de uma missa numa igreja pr\u00f3xima \u2014 que n\u00e3o&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":9040,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[407],"tags":[],"class_list":["post-9039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conto-gay"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3 - Foto de Penis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3 - Foto de Penis\" \/>\n<meta property=\"og:description\" content=\"eu morria de \u00f3dio daquilo! Durante uma manh\u00e3 t\u00edpica de domingo na fazenda, minha m\u00e3e, av\u00f3 e tias e tios participavam de uma missa numa igreja pr\u00f3xima \u2014 que n\u00e3o....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Foto de Penis\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-15T02:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fotodepenis.com\/wp-content\/uploads\/2022\/11\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Homens Pelados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Homens Pelados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/\"},\"author\":{\"name\":\"Homens Pelados\",\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/#\\\/schema\\\/person\\\/b134975191178c742f767879079e08e5\"},\"headline\":\"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3\",\"datePublished\":\"2022-11-15T02:09:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/\"},\"wordCount\":1122,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fotodepenis.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg\",\"articleSection\":[\"Conto Gay\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/\",\"url\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/\",\"name\":\"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3 - Foto de Penis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fotodepenis.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg\",\"datePublished\":\"2022-11-15T02:09:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/#\\\/schema\\\/person\\\/b134975191178c742f767879079e08e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fotodepenis.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg\",\"contentUrl\":\"https:\\\/\\\/fotodepenis.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg\",\"width\":600,\"height\":337,\"caption\":\"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/o-segredo-do-meu-irmaozinho-parte-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fotodepenis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conto Gay\",\"item\":\"https:\\\/\\\/fotodepenis.com\\\/conto-gay\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/#website\",\"url\":\"https:\\\/\\\/fotodepenis.com\\\/\",\"name\":\"Foto de Penis\",\"description\":\"Homens Pelados, Famosos nus, Foto de Pau\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fotodepenis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fotodepenis.com\\\/#\\\/schema\\\/person\\\/b134975191178c742f767879079e08e5\",\"name\":\"Homens Pelados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e3c69029b825f9d3e95b5a21032e2935c6575f7b5ab42c97a483ceaadd660e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e3c69029b825f9d3e95b5a21032e2935c6575f7b5ab42c97a483ceaadd660e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e3c69029b825f9d3e95b5a21032e2935c6575f7b5ab42c97a483ceaadd660e2?s=96&d=mm&r=g\",\"caption\":\"Homens Pelados\"},\"sameAs\":[\"https:\\\/\\\/fotodepenis.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3 - Foto de Penis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/","og_locale":"pt_BR","og_type":"article","og_title":"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3 - Foto de Penis","og_description":"eu morria de \u00f3dio daquilo! Durante uma manh\u00e3 t\u00edpica de domingo na fazenda, minha m\u00e3e, av\u00f3 e tias e tios participavam de uma missa numa igreja pr\u00f3xima \u2014 que n\u00e3o....","og_url":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/","og_site_name":"Foto de Penis","article_published_time":"2022-11-15T02:09:53+00:00","og_image":[{"width":600,"height":337,"url":"https:\/\/fotodepenis.com\/wp-content\/uploads\/2022\/11\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg","type":"image\/jpeg"}],"author":"Homens Pelados","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Homens Pelados","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/#article","isPartOf":{"@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/"},"author":{"name":"Homens Pelados","@id":"https:\/\/fotodepenis.com\/#\/schema\/person\/b134975191178c742f767879079e08e5"},"headline":"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3","datePublished":"2022-11-15T02:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/"},"wordCount":1122,"commentCount":0,"image":{"@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/fotodepenis.com\/wp-content\/uploads\/2022\/11\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg","articleSection":["Conto Gay"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/","url":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/","name":"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3 - Foto de Penis","isPartOf":{"@id":"https:\/\/fotodepenis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/#primaryimage"},"image":{"@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/fotodepenis.com\/wp-content\/uploads\/2022\/11\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg","datePublished":"2022-11-15T02:09:53+00:00","author":{"@id":"https:\/\/fotodepenis.com\/#\/schema\/person\/b134975191178c742f767879079e08e5"},"breadcrumb":{"@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/#primaryimage","url":"https:\/\/fotodepenis.com\/wp-content\/uploads\/2022\/11\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg","contentUrl":"https:\/\/fotodepenis.com\/wp-content\/uploads\/2022\/11\/conto-gay-o-segredo-do-meu-irmaozinho-parte-3.jpg","width":600,"height":337,"caption":"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3"},{"@type":"BreadcrumbList","@id":"https:\/\/fotodepenis.com\/conto-gay\/o-segredo-do-meu-irmaozinho-parte-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fotodepenis.com\/"},{"@type":"ListItem","position":2,"name":"Conto Gay","item":"https:\/\/fotodepenis.com\/conto-gay\/"},{"@type":"ListItem","position":3,"name":"O SEGREDO DO MEU IRM\u00c3OZINHO \u2013 Parte 3"}]},{"@type":"WebSite","@id":"https:\/\/fotodepenis.com\/#website","url":"https:\/\/fotodepenis.com\/","name":"Foto de Penis","description":"Homens Pelados, Famosos nus, Foto de Pau","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fotodepenis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/fotodepenis.com\/#\/schema\/person\/b134975191178c742f767879079e08e5","name":"Homens Pelados","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5e3c69029b825f9d3e95b5a21032e2935c6575f7b5ab42c97a483ceaadd660e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e3c69029b825f9d3e95b5a21032e2935c6575f7b5ab42c97a483ceaadd660e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e3c69029b825f9d3e95b5a21032e2935c6575f7b5ab42c97a483ceaadd660e2?s=96&d=mm&r=g","caption":"Homens Pelados"},"sameAs":["https:\/\/fotodepenis.com"]}]}},"_links":{"self":[{"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/posts\/9039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/comments?post=9039"}],"version-history":[{"count":0,"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/posts\/9039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/media\/9040"}],"wp:attachment":[{"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/media?parent=9039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/categories?post=9039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fotodepenis.com\/wp-json\/wp\/v2\/tags?post=9039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}